{"id":24034,"count":3,"description":"","link":"https:\/\/javmost.me\/zh-hans\/actor\/%e4%ba%94%e5%8d%81%e5%b2%9a%e6%b8%85%e6%b1%a0\/","name":"\u4e94\u5341\u5c9a\u6e05\u6c60","slug":"%e4%ba%94%e5%8d%81%e5%b2%9a%e6%b8%85%e6%b1%a0","taxonomy":"actors","meta":[],"_links":{"self":[{"href":"https:\/\/javmost.me\/zh-hans\/wp-json\/wp\/v2\/actors\/24034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/javmost.me\/zh-hans\/wp-json\/wp\/v2\/actors"}],"about":[{"href":"https:\/\/javmost.me\/zh-hans\/wp-json\/wp\/v2\/taxonomies\/actors"}],"wp:post_type":[{"href":"https:\/\/javmost.me\/zh-hans\/wp-json\/wp\/v2\/posts?actors=24034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}