{"id":79968,"date":"2025-01-17T04:46:06","date_gmt":"2025-01-16T21:46:06","guid":{"rendered":"https:\/\/missav.plus\/hunta-226-festa-de-sexo-da-amiga-da-mamae\/"},"modified":"2025-01-17T04:46:06","modified_gmt":"2025-01-16T21:46:06","slug":"hunta-226-festa-de-sexo-da-amiga-da-mamae","status":"publish","type":"post","link":"https:\/\/javmost.me\/pt-br\/hunta-226-festa-de-sexo-da-amiga-da-mamae\/","title":{"rendered":"HUNTA-226 Festa de sexo da amiga da mam\u00e3e"},"content":{"rendered":"<p>HUNTA-226 Festa de sexo da amiga da mam\u00e3e Sinopse Sua m\u00e3e trouxe seus amigos para uma festa em casa, mas parecia que cada um deles queria fazer algo assim com ele.<br \/>\n<iframe loading=\"lazy\" class=\"videowrapper\" src=\"https:\/\/fembeqq.xyz\/player\/index.php?data=f6556dfe948f58c57650fc8c13294030\" width=\"300\" height=\"175\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>HUNTA-226 Festa de sexo da amiga da mam\u00e3e Sinopse Sua m\u00e3e trouxe seus amigos para uma festa em casa, mas parecia que cada um deles queria fazer algo assim com ele. [&#8230;]<\/p>\n<p><a class=\"btn btn-primary wpst-read-more-link\" href=\"https:\/\/javmost.me\/pt-br\/hunta-226-festa-de-sexo-da-amiga-da-mamae\/\">Read More&#8230;<\/a><\/p>\n","protected":false},"author":4,"featured_media":79952,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12419,12326,12333],"tags":[12835,13165,12746,12889,26851,27017],"actors":[],"class_list":["post-79968","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-av-gangbang-pt-br","category-av-japao","category-av-ntr-pt-br","tag-amiga-da-mamae","tag-cercado","tag-festa-de-sexo","tag-hunta-pt-br","tag-mulheres-casadas","tag-promiscuo"],"_links":{"self":[{"href":"https:\/\/javmost.me\/pt-br\/wp-json\/wp\/v2\/posts\/79968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/javmost.me\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/javmost.me\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/javmost.me\/pt-br\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/javmost.me\/pt-br\/wp-json\/wp\/v2\/comments?post=79968"}],"version-history":[{"count":0,"href":"https:\/\/javmost.me\/pt-br\/wp-json\/wp\/v2\/posts\/79968\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/javmost.me\/pt-br\/wp-json\/wp\/v2\/media\/79952"}],"wp:attachment":[{"href":"https:\/\/javmost.me\/pt-br\/wp-json\/wp\/v2\/media?parent=79968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/javmost.me\/pt-br\/wp-json\/wp\/v2\/categories?post=79968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/javmost.me\/pt-br\/wp-json\/wp\/v2\/tags?post=79968"},{"taxonomy":"actors","embeddable":true,"href":"https:\/\/javmost.me\/pt-br\/wp-json\/wp\/v2\/actors?post=79968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}