{"id":3131,"count":19,"description":"","link":"https:\/\/javmost.me\/en\/actor\/karen-kaede-en\/","name":"Karen Kaede","slug":"karen-kaede-en","taxonomy":"actors","meta":[],"_links":{"self":[{"href":"https:\/\/javmost.me\/en\/wp-json\/wp\/v2\/actors\/3131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/javmost.me\/en\/wp-json\/wp\/v2\/actors"}],"about":[{"href":"https:\/\/javmost.me\/en\/wp-json\/wp\/v2\/taxonomies\/actors"}],"wp:post_type":[{"href":"https:\/\/javmost.me\/en\/wp-json\/wp\/v2\/posts?actors=3131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}