{"id":21045,"count":1,"description":"","link":"https:\/\/javmost.me\/en\/actor\/silvia-dellai-en\/","name":"Silvia Dellai","slug":"silvia-dellai-en","taxonomy":"actors","meta":[],"_links":{"self":[{"href":"https:\/\/javmost.me\/en\/wp-json\/wp\/v2\/actors\/21045","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/javmost.me\/en\/wp-json\/wp\/v2\/actors"}],"about":[{"href":"https:\/\/javmost.me\/en\/wp-json\/wp\/v2\/taxonomies\/actors"}],"wp:post_type":[{"href":"https:\/\/javmost.me\/en\/wp-json\/wp\/v2\/posts?actors=21045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}