{"id":19372,"count":1,"description":"","link":"https:\/\/javmost.me\/de\/actor\/jessica-bangkok-de\/","name":"Jessica Bangkok","slug":"jessica-bangkok-de","taxonomy":"actors","meta":[],"_links":{"self":[{"href":"https:\/\/javmost.me\/de\/wp-json\/wp\/v2\/actors\/19372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/javmost.me\/de\/wp-json\/wp\/v2\/actors"}],"about":[{"href":"https:\/\/javmost.me\/de\/wp-json\/wp\/v2\/taxonomies\/actors"}],"wp:post_type":[{"href":"https:\/\/javmost.me\/de\/wp-json\/wp\/v2\/posts?actors=19372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}