{"id":10097,"count":3,"description":"","link":"https:\/\/javmost.me\/de\/actor\/maschenka\/","name":"Maschenka","slug":"maschenka","taxonomy":"actors","meta":[],"_links":{"self":[{"href":"https:\/\/javmost.me\/de\/wp-json\/wp\/v2\/actors\/10097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/javmost.me\/de\/wp-json\/wp\/v2\/actors"}],"about":[{"href":"https:\/\/javmost.me\/de\/wp-json\/wp\/v2\/taxonomies\/actors"}],"wp:post_type":[{"href":"https:\/\/javmost.me\/de\/wp-json\/wp\/v2\/posts?actors=10097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}